{"id":2476,"date":"2018-08-25T04:05:29","date_gmt":"2018-08-25T03:05:29","guid":{"rendered":"http:\/\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg"},"modified":"2018-08-25T04:05:29","modified_gmt":"2018-08-25T03:05:29","slug":"f46567b2-3d44-4f2f-9282-fe272bdbe596","status":"inherit","type":"attachment","link":"https:\/\/www.bungarten.de\/wordpress\/f46567b2-3d44-4f2f-9282-fe272bdbe596\/","title":{"rendered":"F46567B2-3D44-4F2F-9282-FE272BDBE596"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-2476","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a3plSY-DW","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"432\" src=\"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?fit=650%2C432&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?w=4912&amp;ssl=1 4912w, https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?resize=650%2C432&amp;ssl=1 650w, https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?resize=903%2C600&amp;ssl=1 903w, https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?resize=624%2C415&amp;ssl=1 624w, https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?w=1250&amp;ssl=1 1250w, https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?w=1875&amp;ssl=1 1875w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":4912,"height":3264,"file":"2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg","sizes":{"thumbnail":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?resize=150%2C150&ssl=1"},"medium":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596-650x432.jpeg","width":650,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?fit=650%2C432&ssl=1"},"large":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596-903x600.jpeg","width":903,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?fit=625%2C415&ssl=1"},"gg_gallery_thumbnail":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596-450x250.jpeg","width":450,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?resize=450%2C250&ssl=1"},"post-thumbnail":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596-624x415.jpeg","width":624,"height":415,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?fit=624%2C415&ssl=1"},"about-the-author-userphoto":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596-250x250.jpeg","width":250,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596-250x250.jpeg"},"full":{"file":"F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?fit=4912%2C3264&ssl=1","width":4912,"height":3264,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg?fit=4912%2C3264&ssl=1"}},"image_meta":{"aperture":"5","credit":"","camera":"NEX-3N","caption":"","created_timestamp":"1535011198","copyright":"","focal_length":"16","iso":"200","shutter_speed":"0.0025","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2018\/08\/F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg","filename":"F46567B2-3D44-4F2F-9282-FE272BDBE596.jpeg","filesize":6553600,"_links":{"self":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/media\/2476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/comments?post=2476"}]}}