{"id":86,"date":"2012-07-20T18:14:45","date_gmt":"2012-07-20T16:14:45","guid":{"rendered":"http:\/\/www.bungarten.de\/wordpress\/?p=86"},"modified":"2013-05-06T09:39:59","modified_gmt":"2013-05-06T07:39:59","slug":"37-stunden-on-the-road","status":"publish","type":"post","link":"https:\/\/www.bungarten.de\/wordpress\/2012\/07\/20\/37-stunden-on-the-road\/","title":{"rendered":"37 Stunden on the road &#8230;"},"content":{"rendered":"<h4><\/h4>\n<h4><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" alt=\"\" src=\"https:\/\/i0.wp.com\/lh5.googleusercontent.com\/-PDc76Yn_e90\/UYddOI1JxnI\/AAAAAAAAC0Y\/jBO303mE_PE\/w737-h756\/IMG_0940.JPG?w=600&#038;ssl=1\"  \/><\/h4>\n<h4><strong>37 Stunden \u00bbon the road\u00ab<\/strong>:<\/h4>\n<p>bestehend aus 12 Std.\u00a0auf 3 verschiedenen F\u00e4hren, Formalit\u00e4ten im \u00bbImmigration Office\u00ab (es erinnerte mich sehr an den Film \u00bbder Pate\u00ab mit Marlon Brando, wie er so hinter dem Schreibtisch thronte. F\u00fcrs Foto hat er sich extra sein Uniformhemd angezogen), 3 Std. mit dem \u00bbTrycicle\u00ab (Moped mit Beiwagen, bei dem Eve\u2019s rechte Pobacke immer zu Stabilisierungszwecken gebraucht wurde) durch eine Stadt, in der es 3000 von denen gibt, um einen funktionierenden Geldautomaten zu finden (ohne Erfolg).<\/p>\n<p>Bevor ich\u2019s vergesse: wir mussten unseren kompletten Anreiseplan \u00fcber den Haufen schmei\u00dfen, da eine F\u00e4hre ausfiel, wir aber den Flieger kriegen mussten. Geplant war, nach den erledigten Formalit\u00e4ten in Surigao die F\u00e4hre nach Cebu zu nehmen, um dort in den Flieger zu steigen. Die einzig m\u00f6gliche F\u00e4hre wurde aber ersatzlos gestrichen (was hier nichts ungew\u00f6hnliches ist).<\/p>\n<p>Jetzt war guter Rat teuer &#8211; es gab nur eine Alternative und die lie\u00df zeitlich nicht viel Spielraum: mit dem \u00bbTrycicle\u00ab zum 10 km entfernten F\u00e4hrhafen in \u00bbLipata\u00ab und das ist nicht wirklich lustig. Bei jeder kleineren Steigung stand der Rasenm\u00e4hermotor kurz vor\u2019m Exitus und mein Vorschlag, bergauf ein bi\u00dfchen anschieben zu wollen, lehnte er entr\u00fcstet ab.<\/p>\n<p>Jedenfalls schafften wir es rechtzeitig, die F\u00e4hre zu bekommen. Nach der Ankunft in \u00bbLiloan\u00ab mussten wir ein Transportmittel finden, um nach \u00bbBato\u00ab zu kommen, in der Hoffnung, dort eine Nachtf\u00e4hre zu erreichen, die uns in Cebu den Flieger erreichen lassen konnte. Es war letztlich ein \u00bbJeepney\u00ab, der uns nach Bato bringen sollte &#8211; ein grellbuntes abenteuerliches Gef\u00e4hrt, das seinen Ursprung in den von GI\u2019S zur\u00fcckgelassenen Jeeps aus dem 2. Weltkrieg hat. Diese Fahrzeuge sind die \u00f6ffentlichen Transportmittel f\u00fcr den Fernverkehr und transportieren Alles: Post, Pakete, Menschen, Tiere, Hausrat, Warenlieferungen f\u00fcr jegliche Kioske und daf\u00fcr begleiten neben dem Fahrer noch zwei weitere, meist j\u00fcngere Filippinos, die Busse und turnen w\u00e4hrend der Fahrt mehr auf dem Dach oder der K\u00fchlerhaube herum, um permanent Gep\u00e4ckst\u00fccke o.\u00e4. auf- oder abzuladen und gleichzeitig noch zu kassieren. Angehalten wird durch heftiges Klopfen gegen das Wagendach. Erst w\u00e4hrend der Fahrt und mit Hilfe Randys, einem einheimischen \u00fcberaus hilfsbereiten Pfarrers, bekamen wir die Info, dass es wohl klappen w\u00fcrde und auch tat.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone\" alt=\"\" src=\"https:\/\/i0.wp.com\/lh3.googleusercontent.com\/-Z-jpK9_Oq2Q\/UYddj24iSvI\/AAAAAAAAC0g\/_NXC9QhjJNw\/w1125-h749\/DSC01491.JPG?w=625&#038;ssl=1\"  \/><\/p>\n<p>Also F\u00e4hre mit Kabine gebucht in der mir die Klimaanlage ziemlich auf den Senkel ging und wir gefroren haben wie ein Hund ohne Fell. Am Morgen in \u00bbPuerta Princesa\u00ab dann per Taxi zum Busterminal und dann wieder mit dem \u00bbJeepney\u00ab zu unserem Ziel, dem Ort \u00bb<a href=\"http:\/\/maps.google.de\/maps?hl=de&amp;q=sabang%20palawan&amp;um=1&amp;ie=UTF-8&amp;sa=N&amp;tab=wl\">Sabang<\/a>\u00ab im Nordwesten von Palawan. Der Rest setzte sich dann aus diversen Wartezeiten zusammen und zum Schluss sieht man dann so entspannt aus, wie auf dem Bild &#8211; das nenne ich dann mal entspanntes Reisen &#8230;<\/p>\n<p>Noch\u2019n paar Impressionen zum \u00bbentspannten Reisen\u00ab: Luxussitze auf der F\u00e4hre, das Motto \u00bbno fear\u00ab (warum wohl?) direkt auf den Jeepney lackiert, Essen auf R\u00e4der w\u00e4hrend der Busfahrt und die Standardversion des \u00bbTrycicle\u00ab &#8230;<\/p>\n<p>Fortsetzung folgt &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>37 Stunden \u00bbon the road\u00ab: bestehend aus 12 Std.\u00a0auf 3 verschiedenen F\u00e4hren, Formalit\u00e4ten im \u00bbImmigration Office\u00ab (es erinnerte mich sehr an den Film \u00bbder Pate\u00ab mit Marlon Brando, wie er so hinter dem Schreibtisch thronte. F\u00fcrs Foto hat er sich extra sein Uniformhemd angezogen), 3 Std. mit dem \u00bbTrycicle\u00ab (Moped mit Beiwagen, bei dem Eve\u2019s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[19,15,85],"class_list":["post-86","post","type-post","status-publish","format-standard","hentry","category-philippinen","tag-jeepney","tag-palawan","tag-philippinen"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3plSY-1o","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":10,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts\/86\/revisions"}],"predecessor-version":[{"id":89,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts\/86\/revisions\/89"}],"wp:attachment":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/media?parent=86"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/categories?post=86"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/tags?post=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}