{"id":962,"date":"2014-07-28T13:36:44","date_gmt":"2014-07-28T11:36:44","guid":{"rendered":"http:\/\/www.bungarten.de\/wordpress\/?p=962"},"modified":"2016-02-21T18:37:27","modified_gmt":"2016-02-21T16:37:27","slug":"der-hi-tec-wahnsinn","status":"publish","type":"post","link":"https:\/\/www.bungarten.de\/wordpress\/2014\/07\/28\/der-hi-tec-wahnsinn\/","title":{"rendered":"Der Hi-Tec Wahnsinn &#8230;"},"content":{"rendered":"<p>Es ist der Wahnsinn, was mittlerweile f\u00fcr eine Menge an elektronischem Krims-Krams mit auf eine Radreise \u00fcber mehrere Wochen geht &#8211; und das alles nur, weil ich in dem Glauben bin, dass es zu meinem Standard geh\u00f6rt, keine Stra\u00dfenkarte mehr auseinander falten, die Reise in bewegten Bildern dokumentieren und das Alles m\u00f6glichst zeitnah an all die uninteressierten \u00bbFreunde\u00ab bei Facebook oder Zuhause ver\u00f6ffentlichen zu m\u00fcssen.<\/p>\n<p><strong>Oder bereitet es mir einfach nur Spa\u00df und Freude &#8230;<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2014\/07\/20140728-123208-45128297.jpg?w=625&#038;ssl=1\" alt=\"20140728-123208-45128297.jpg\" \/><\/p>\n<p>Ich habe mir heute mal die Zeit genommen und mein komplettes Equipment zusammen getragen und bildlich fest gehalten &#8211; es ist doch Einiges &#8230;<\/p>\n<p><strong>Um es mal aufzuz\u00e4hlen:<\/strong><\/p>\n<p>Das Ganze mu\u00df ja mit Energie versorgt werden. Voraussetzung ist ein Nabendynamo zur Stromproduktion, der meinen Akkulader inkl. Pufferakku &#8211; den <strong>Zzing<\/strong> &#8211; mit Strom versorgt und l\u00e4dt. Normalerweise soll der Akku nach ca. 30 Minuten und einer Durchschnittsgeschwindigkeit von ca. 15 km\/h gen\u00fcgend Strom gespeichert haben, um ihn an mein <strong>iPhone 5<\/strong> abgeben zu k\u00f6nnen. Das klappt aber leider nicht, obwohl ich mittlerweile einen Akku mit mehr Leistung ins <strong>Zzing<\/strong> eingebaut habe. Wahrscheinlich bin ich einfach zu langsam &#8230; \ud83d\ude41 So bin ich gezwungen, ihn in der Nacht per externem Ladeger\u00e4t aufzuladen.<\/p>\n<p>Aber es ist ja nicht so, dass ich keine Alternativen habe: den <strong>Akku von Anker<\/strong> mit 15000 mAh und 2 USB-Anschl\u00fcssen, die mein iPhone mehrmals aufladen k\u00f6nnen und selbst das <strong>iPad<\/strong> mit Strom versorgen.<\/p>\n<p>Nat\u00fcrlich habe ich f\u00fcr die Aufladung der diversen Akkus gesorgt, und Stromadapter f\u00fcr Camping (auf&#8217;m Foto vergessen) dabei &#8211; ein Stromanschluss auf&#8217;m Platz ist also mittlerweile Voraussetzung.<\/p>\n<p>Die komplette Navigation l\u00e4uft \u00fcber mein iPhone (nat\u00fcrlich mit wasserdichter H\u00fclle &#8211; was nicht unwichtig war auf unserer Reise) und den entsprechenden Apps: <strong>komoot<\/strong> und in Ausnahmef\u00e4llen <strong>MotionX-GPS<\/strong>. Die meisten Strecken habe ich zuhause am PC auf Basecamp ausgearbeitet und auf <a href=\"http:\/\/www.komoot.de\">komoot.de<\/a> \u00fcbertragen, sodass ich von \u00fcberall darauf Zugriff habe. Voraussetzung daf\u00fcr ist eine Datentarifkarte f\u00fcr&#8217;s iPhone, die ich mir im Vorfeld besorgt habe. Auch die Dokumention der Strecken l\u00e4uft \u00fcber <strong>komoot<\/strong> &#8211; die Kombination mit den per iPhone geschossenen Fotos gef\u00e4llt mir besonders.<\/p>\n<p>Das <strong>Garmin Edge 705<\/strong> ist nur noch Backup und f\u00fcr dir erg\u00e4nzenden Infos, wie H\u00f6hendaten etc.<\/p>\n<p>Neu in meiner Ausstattung ist die <strong>GoPro Hero3+ Black Edition<\/strong> mit jeder Menge Zubeh\u00f6r, die ich am Lenker montiert habe und mit der ich w\u00e4hrend der Fahrt immer wieder kleinere Takes mache. Dazu mehrere Akkus, die nat\u00fcrlich auch geladen werden m\u00fcssen.<\/p>\n<p>F\u00fcr die &#8222;normalen&#8220; Fotos ist unsere <strong>Sony NEX3<\/strong> zust\u00e4ndig, die in erster Linie von Eve eingesetzt wird.<\/p>\n<p>Da B\u00fccher sowohl schwer sind und viel Platz einnehmen, haben wir auch da aufger\u00fcstet und sind im Besitz von zwei <strong>Kindles<\/strong>, die wir nicht mehr missen m\u00f6chten.<\/p>\n<p>Da alle diese Ger\u00e4te ja auch irgendwie geladen werden m\u00fcssen und der Platz f\u00fcr das jeweilige Netzteil fehlt, kommen wir zu einem der besten Tools: dem <strong>USB-Ladeger\u00e4t von Anker<\/strong> mit 5 USB-Anschl\u00fcssen. Damit k\u00f6nnen bis zu 5 Ger\u00e4te gleichzeitig geladen werden, auch ein solch energiebed\u00fcrftiges Teil wie das <strong>iPad Air<\/strong>, mit dem ich die ganzen Beitr\u00e4ge schreibe, Fotos bearbeite, Videos erstelle und all die dummen Kommentare niederschreibe &#8230;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2014\/07\/20140728-123208-45128544.jpg?ssl=1\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"alignnone size-full\" src=\"https:\/\/i0.wp.com\/www.bungarten.de\/wordpress\/wp-content\/uploads\/2014\/07\/20140728-123208-45128544.jpg?w=625&#038;ssl=1\" alt=\"20140728-123208-45128544.jpg\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist der Wahnsinn, was mittlerweile f\u00fcr eine Menge an elektronischem Krims-Krams mit auf eine Radreise \u00fcber mehrere Wochen geht &#8211; und das alles nur, weil ich in dem Glauben bin, dass es zu meinem Standard geh\u00f6rt, keine Stra\u00dfenkarte mehr auseinander falten, die Reise in bewegten Bildern dokumentieren und das Alles m\u00f6glichst zeitnah an all [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[46],"tags":[9,91,97],"class_list":["post-962","post","type-post","status-publish","format-standard","hentry","category-radreise","tag-italien","tag-radreise","tag-zubehoer"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3plSY-fw","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts\/962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":7,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"predecessor-version":[{"id":980,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/posts\/962\/revisions\/980"}],"wp:attachment":[{"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bungarten.de\/wordpress\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}